{"id":6155,"date":"2020-07-09T08:56:00","date_gmt":"2020-07-09T06:56:00","guid":{"rendered":"https:\/\/daes.pro\/non-categorizzato\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/"},"modified":"2023-11-15T17:16:03","modified_gmt":"2023-11-15T16:16:03","slug":"tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere","status":"publish","type":"post","link":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/","title":{"rendered":"Tutto quello che avreste sempre voluto sapere sulla gestione delle scorie nucleari (ma che avevate paura di chiedere)!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"6155\" class=\"elementor elementor-6155 elementor-3166\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-628db73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"628db73\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;0079ebc&quot;,&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;50&quot;,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_bg_x&quot;:&quot;50&quot;,&quot;jet_parallax_layout_bg_y&quot;:&quot;50&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-ca1274b\" data-id=\"ca1274b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe89205 elementor-mobile-align-center elementor-align-left elementor-widget elementor-widget-raven-heading\" data-id=\"fe89205\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h3 class=\"raven-heading raven-heading-h3\"><span class=\"raven-heading-title \">Rifiuti MA-VL e HA da combustibile irradiato nelle centrali nucleari\n<\/span><\/h3><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c83dd0c elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-raven-post-meta\" data-id=\"c83dd0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-post-meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"raven-inline-items raven-icon-list-items raven-post-meta\">\n\t\t\t\t\t<li class=\"raven-icon-list-item elementor-repeater-item-f8d3d44 raven-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"raven-icon-list-text raven-post-meta-item raven-post-meta-item-type-date\">\n\t\t\t\t\t\t\t\t\t\tLuglio 9, 2020\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"raven-icon-list-item elementor-repeater-item-bbb15c9 raven-inline-item\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"raven-icon-list-text raven-post-meta-item raven-post-meta-item-type-terms raven-terms-list\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"raven-post-meta-terms-list\">\n\t\t\t\t<a href=\"https:\/\/daes.pro\/it\/category\/articoli\/\" class=\"raven-post-meta-terms-list-item\">Articoli<\/a>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76dc315 elementor-widget elementor-widget-text-editor\" data-id=\"76dc315\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Una delle principali sfide dell&#8217;<a href=\"https:\/\/daes.pro\/portfolio\/energie\/\" target=\"_blank\" rel=\"noopener noreferrer\">energia nucleare<\/a> \u00e8 la gestione e lo stoccaggio delle scorie nucleari ad alta attivit\u00e0 e a lunga vita. Rimangono pericolosamente radioattivi per centinaia di migliaia di anni (generalmente 200.000 anni) e richiedono un trattamento speciale, regolato dai governi che garantiscono la sicurezza pubblica. In Francia, i rifiuti nucleari sono gestiti dall&#8217;<a href=\"https:\/\/www.andra.fr\/les-dechets-radioactifs\" target=\"_blank\" rel=\"noopener noreferrer\">ANDRA <\/a>. Sono classificati in base a due caratteristiche principali: la pericolosit\u00e0 e la durata di vita. Queste caratteristiche sono suddivise in sei categorie di rifiuti. In questo articolo ci concentriamo sulle due categorie seguenti:<\/p>\n<ul>\n<li><strong>Rifiuti a vita lunga a livello intermedio (ILW)<\/strong><\/li>\n<li><strong>Rifiuti ad alta attivit\u00e0<\/strong><\/li>\n<\/ul>\n<p>La maggior parte della <strong>LV-AM<\/strong> proviene da strutture di supporto del combustibile nucleare, ad esempio il rivestimento del gruppo di combustibile <strong>in zirconio<\/strong>. Questi rifiuti vengono compattati per ridurne il volume e poi imballati in contenitori di metallo o di cemento. Rappresenta il 3% in volume di tutti i rifiuti nucleari prodotti in Francia.<\/p>\n<p>L&#8217;<strong>HA<\/strong> proviene dal trattamento del combustibile esaurito. Si tratta di residui che non possono essere riutilizzati, come gli attinidi o i prodotti di fissione. Vengono carbonizzati e poi vetrificati. La miscela vetro-rifiuti (3% di rifiuti, 97% di vetro, in massa) viene imballata in confezioni di acciaio inossidabile, che a volte sono collocate in un secondo contenitore di acciaio. Questi rifiuti <strong>HA<\/strong> rappresentano lo 0,2% in volume di tutti i rifiuti nucleari prodotti in Francia. Concentrano il 96% della radioattivit\u00e0.<\/p>\n<p>Queste due categorie di rifiuti<strong>(MA-VL e HA<\/strong>) rappresentano una piccola percentuale della massa o del volume totale dei rifiuti nucleari. Tuttavia, hanno un&#8217;emivita di diverse centinaia di migliaia di anni e sono altamente tossici. Sono tutti derivati dal combustibile esaurito. Una soluzione in fase di studio \u00e8 lo stoccaggio reversibile in profondit\u00e0.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0b42629\" data-id=\"0b42629\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e99b2b elementor-widget elementor-widget-sidebar\" data-id=\"8e99b2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"block-5\" class=\"jupiterx-widget widget_block block-5 widget_block\"><div class=\"jupiterx-widget-content\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<h4 class=\"wp-block-heading\">Categorie<\/h4>\n\n\n<ul class=\"wp-block-categories-list wp-block-categories-taxonomy-category wp-block-categories\">\t<li class=\"cat-item cat-item-147\"><a href=\"https:\/\/daes.pro\/it\/category\/articoli\/\">Articoli<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-246\"><a href=\"https:\/\/daes.pro\/it\/category\/carriera\/\">Carriera<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-249\"><a href=\"https:\/\/daes.pro\/it\/category\/non-classificato\/\">Non classificato<\/a>\n<\/li>\n\t<li class=\"cat-item cat-item-140\"><a href=\"https:\/\/daes.pro\/it\/category\/notizie\/\">Notizie<\/a>\n<\/li>\n<\/ul>\n\n\n<h4 class=\"wp-block-heading arch\">professioni<\/h4>\n\n\n<p class=\"wp-block-tag-cloud\"><a href=\"https:\/\/daes.pro\/it\/tag\/analisi-dinamica\/\" class=\"tag-cloud-link tag-link-241 btn btn-light tag-link-position-1\" style=\"font-size: 10pt;\" aria-label=\"Analisi dinamica (3 elementi)\">Analisi dinamica<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/analisi-elettromagnetica\/\" class=\"tag-cloud-link tag-link-154 btn btn-light tag-link-position-2\" style=\"font-size: 10pt;\" aria-label=\"Analisi elettromagnetica (2 elementi)\">Analisi elettromagnetica<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/analisi-meccanica\/\" class=\"tag-cloud-link tag-link-250 btn btn-light tag-link-position-3\" style=\"font-size: 10pt;\" aria-label=\"Analisi meccanica (1 elemento)\">Analisi meccanica<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/applicazioni\/\" class=\"tag-cloud-link tag-link-160 btn btn-light tag-link-position-4\" style=\"font-size: 10pt;\" aria-label=\"Applicazioni (5 elementi)\">Applicazioni<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/cfd-it\/\" class=\"tag-cloud-link tag-link-148 btn btn-light tag-link-position-5\" style=\"font-size: 10pt;\" aria-label=\"CFD (6 elementi)\">CFD<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/energia-cleantech\/\" class=\"tag-cloud-link tag-link-238 btn btn-light tag-link-position-6\" style=\"font-size: 10pt;\" aria-label=\"Energia CleanTech (1 elemento)\">Energia CleanTech<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/ingegneria-del-pensiero-progettuale\/\" class=\"tag-cloud-link tag-link-150 btn btn-light tag-link-position-7\" style=\"font-size: 10pt;\" aria-label=\"Ingegneria del pensiero progettuale (2 elementi)\">Ingegneria del pensiero progettuale<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/nucleare\/\" class=\"tag-cloud-link tag-link-151 btn btn-light tag-link-position-8\" style=\"font-size: 10pt;\" aria-label=\"Nucleare (6 elementi)\">Nucleare<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/simulazione-della-fisica-delle-particelle\/\" class=\"tag-cloud-link tag-link-159 btn btn-light tag-link-position-9\" style=\"font-size: 10pt;\" aria-label=\"Simulazione della fisica delle particelle (2 elementi)\">Simulazione della fisica delle particelle<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/simulazione-di-processo\/\" class=\"tag-cloud-link tag-link-149 btn btn-light tag-link-position-10\" style=\"font-size: 10pt;\" aria-label=\"Simulazione di processo (1 elemento)\">Simulazione di processo<\/a>\n<a href=\"https:\/\/daes.pro\/it\/tag\/termomeccanica\/\" class=\"tag-cloud-link tag-link-167 btn btn-light tag-link-position-11\" style=\"font-size: 10pt;\" aria-label=\"Termomeccanica (2 elementi)\">Termomeccanica<\/a><\/p><\/div><\/div>\n<\/div><\/div><span class=\"jupiterx-widget-divider\"><\/span><div id=\"block-8\" class=\"jupiterx-widget widget_block block-8 widget_block\"><div class=\"jupiterx-widget-content\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><\/div>\n<\/div><\/div><span class=\"jupiterx-widget-divider\"><\/span><div id=\"block-9\" class=\"jupiterx-widget widget_block block-9 widget_block\"><div class=\"jupiterx-widget-content\">\n<ul class=\"wp-block-list\">\n<li><\/li>\n\n\n\n<li><\/li>\n<\/ul>\n<\/div><\/div><span class=\"jupiterx-widget-divider\"><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5143c66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5143c66\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;0079ebc&quot;,&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;50&quot;,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_bg_x&quot;:&quot;50&quot;,&quot;jet_parallax_layout_bg_y&quot;:&quot;50&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff79056\" data-id=\"ff79056\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cca6841 elementor-widget elementor-widget-text-editor\" data-id=\"cca6841\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Gestione dei rifiuti MA-VL e HA<\/h3>\nQuesti rifiuti vengono gestiti in due fasi:\n<ol>\n \t<li><strong>Stoccaggio<\/strong>: \u00e8 temporaneo e si basa sul principio dell&#8217;evacuazione termica continua per consentire il raffreddamento del combustibile irradiato.<\/li>\n \t<li><strong>Stoccaggio:<\/strong> \u00e8 definitivo e si basa sul principio della diminuzione dei livelli di radioattivit\u00e0 nel combustibile irradiato.<\/li>\n<\/ol>\nIn questo articolo forniamo una panoramica di queste due fasi di gestione, dei loro principi di funzionamento e dei loro limiti dal punto di vista dello sviluppo sostenibile.\n<h4>Stoccaggio temporaneo di rifiuti radioattivi<\/h4>\nSi distinguono due categorie di sistemi di stoccaggio temporaneo: pool e dry.\n<h5>Deposito della piscina  <\/h5>\n<ul>\n \t<li>\n<h6>PRINCIPIO<\/h6>\n<\/li>\n<\/ul>\nUna volta scaricati dal reattore, gli elementi di combustibile irradiati vengono conservati per almeno cinque anni in vasche d&#8217;acqua situate nello stesso edificio che ospita il reattore nucleare. Ciascuno di questi elementi combustibili \u00e8 immagazzinato in celle disposte in una griglia sul fondo delle piscine.\n<ul>\n \t<li>\n<h6>PISCINA DI STOCCAGGIO<\/h6>\n<\/li>\n<\/ul>\nLe piscine sono costruite in cemento armato e le loro pareti sono rivestite in acciaio saldato. Sono progettati per evitare perdite e resistere agli eventi esterni. La funzione principale dell&#8217;acqua nelle piscine \u00e8 quella di raffreddare il combustibile nucleare irradiato nelle prime fasi del suo decadimento radioattivo. Questo processo consente di rimuovere continuamente il calore residuo generato dal combustibile.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e448da7 elementor-widget elementor-widget-raven-image\" data-id=\"e448da7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\n\t\t\n\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"896\" height=\"598\" src=\"https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/piscine-de-stockage-areva-daes-blog-2020.jpg\" class=\"attachment-full size-full wp-image-5663\" alt=\"\" srcset=\"https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/piscine-de-stockage-areva-daes-blog-2020.jpg 896w, https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/piscine-de-stockage-areva-daes-blog-2020-300x200.jpg 300w, https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/piscine-de-stockage-areva-daes-blog-2020-768x513.jpg 768w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/>\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Areva - Piscina di stoccaggio di Orano<\/figcaption>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5133e83 elementor-widget elementor-widget-text-editor\" data-id=\"5133e83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n \t<li>\n<h6>INERZIA TERMICA E SCHERMATURA DALLE RADIAZIONI<\/h6>\n<\/li>\n<\/ul>\nGrazie all&#8217;elevato trasferimento di calore nell&#8217;acqua e alla sua alta capacit\u00e0 termica, questo sistema offre un&#8217;elevata inerzia termica e mantiene il rivestimento del combustibile (lega di zircaloy) ben al di sotto del suo punto di fusione. In questo modo si mantiene intatta la prima barriera di contenimento contro la dispersione radioattiva. L&#8217;acqua delle piscine fornisce anche una buona schermatura radiologica contro le radiazioni emesse dal combustibile irradiato.<br><br>\n<h5>Stoccaggio a secco (non utilizzato in Francia)<\/h5>\n<ul>\n \t<li>\n<h6>PRINCIPIO<\/h6>\n<\/li>\n<\/ul>\nQuesto <em> sistema di<\/em> stoccaggio temporaneo <em>&#8211; a medio e lungo termine &#8211;<\/em> \u00e8 progettato per ospitare nello stesso Paese il combustibile esaurito e i rifiuti altamente radioattivi per un determinato periodo (fino a 100 anni).\n<ul>\n \t<li>\n<h6>STRUTTURA DI STOCCAGGIO<\/h6>\n<\/li>\n<\/ul>\nIn genere, i rifiuti vengono stoccati in contenitori metallici o di cemento o in vani con specifici sistemi di rimozione del calore. Questo \u00e8 possibile solo dopo un periodo di raffreddamento nelle piscine delle centrali nucleari (vedi sopra). Le strutture di stoccaggio temporaneo sono situate in superficie o a una profondit\u00e0 relativamente bassa. Possono essere situati all&#8217;interno o all&#8217;esterno dell&#8217;impianto. In quest&#8217;ultimo caso, l&#8217;impianto di stoccaggio pu\u00f2 contenere combustibile irraggiato proveniente da uno o pi\u00f9 EPR.\n<ul>\n \t<li>\n<h6>SCHERMATURA ANTIRADIAZIONI<\/h6>\n<\/li>\n<\/ul>\nQueste strutture sono costituite da una struttura in cemento che offre schermatura dalle radiazioni e sicurezza anti-intrusione.\n<ul>\n \t<li>\n<h6>LIMITE<\/h6>\n<\/li>\n<\/ul>\nIn nessun caso questa soluzione pu\u00f2 essere considerata definitiva, n\u00e9 pu\u00f2 essere estesa all&#8217;infinito.<br><br>\n\n<h5>Immagazzinamento<\/h5>\n<ul>\n \t<li>\n<h6><strong> <\/strong><b>DEPOSITI GEOLOGICI<\/b><\/h4>\n<\/li>\n<\/ul>\nQuesta soluzione prevede di isolare i rifiuti interponendo una serie di strati in strutture di stoccaggio a circa 500 metri di profondit\u00e0. I rifiuti vengono prima collocati in contenitori metallici estremamente spessi, che resistono alla corrosione e ad altre forme di danneggiamento per molti anni. Vengono quindi evacuati in tunnel scavati in formazioni geologiche stabili e circondati da un terreno a bassa permeabilit\u00e0 con un&#8217;elevata capacit\u00e0 di ritenzione.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94dea20 elementor-widget elementor-widget-raven-image\" data-id=\"94dea20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\n\t\t\n\t\t<img decoding=\"async\" width=\"866\" height=\"503\" src=\"https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/stockage-mavl-ha-schema-stockage-Cigeo.jpg\" class=\"attachment-full size-full wp-image-5666\" alt=\"\" srcset=\"https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/stockage-mavl-ha-schema-stockage-Cigeo.jpg 866w, https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/stockage-mavl-ha-schema-stockage-Cigeo-300x174.jpg 300w, https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/stockage-mavl-ha-schema-stockage-Cigeo-768x446.jpg 768w\" sizes=\"(max-width: 866px) 100vw, 866px\" \/>\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Stoccaggio MA-VL HA - Schema Cig\u00e9o<\/figcaption>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a690f5a elementor-widget elementor-widget-text-editor\" data-id=\"a690f5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il contenimento e l&#8217;isolamento dei rifiuti sono garantiti da diversi elementi:<\/p>\n<ol>\n<li>il contenitore in cui i rifiuti vengono introdotti prima di essere collocati nella cella di stoccaggio finale.<\/li>\n<li>in alcuni casi, il sovraimballaggio: un supplemento di imballaggio sigillato utilizzato per trasformare le confezioni primarie di rifiuti vetrificati in confezioni per lo stoccaggio o lo smaltimento.<\/li>\n<li>la barriera naturale formata dalla roccia ricevente.<\/li>\n<\/ol>\n<ul>\n<li>\n<h6>PRINCIPIO DELL&#8217;ARCHIVIAZIONE PERMANENTE<\/h6>\n<\/li>\n<\/ul>\n<p>La caratteristica decisiva dello smaltimento finale, rispetto al deposito temporaneo, \u00e8 che l&#8217;obiettivo del recupero dei rifiuti non \u00e8 sistematico. In altre parole, l&#8217;impianto di smaltimento dei rifiuti \u00e8 chiuso e sigillato senza la necessit\u00e0 di un&#8217;ulteriore struttura operativa fuori terra.<\/p>\n<ul>\n<li>\n<h6>RECUPERO DEI RIFIUTI IN QUESTIONE<\/h6>\n<\/li>\n<\/ul>\n<p>In ogni caso, \u00e8 sempre possibile tenere sotto controllo l&#8217;impianto di stoccaggio e il suo ambiente per tutto il tempo ritenuto necessario. L&#8217;impianto pu\u00f2 essere progettato in modo tale che i rifiuti stoccati possano essere recuperati in futuro. ANDRA prevede di rendere reversibile l&#8217;impianto di smaltimento profondo per un periodo di 100 anni.<\/p>\n<ul>\n<li>\n<h6>LIMITI<\/h6>\n<\/li>\n<\/ul>\n<p>Lo smaltimento geologico in profondit\u00e0 richiede dimostrazioni di sicurezza relative :<\/p>\n<ul>\n<li>L&#8217;invecchiamento dei pacchetti di rifiuti sepolti dura diverse migliaia di anni. L&#8217;obiettivo \u00e8 dimostrare che la roccia tratterr\u00e0 le specie radioattive una volta che la corrosione avr\u00e0 danneggiato il contenitore.<\/li>\n<li>Resistenza a eventi geologici come i terremoti.<\/li>\n<li>La memoria della discarica. Ricordare dove si trovano i rifiuti \u00e8 un aspetto fondamentale. Ci\u00f2 significa trasmettere le informazioni a molte generazioni di individui. \u00c8 quindi necessario ideare un mezzo di comunicazione che duri oltre la lingua e un mezzo di comunicazione che non si deteriori.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.andra.fr\/cigeo?gclid=Cj0KCQjwo6D4BRDgARIsAA6uN19R3byAFHgeqZYDjAjsLz3RT4L3AjnG9xsToSaWWyBPfPHgP1o3n9UaAtf-EALw_wcB\" target=\"_blank\" rel=\"noopener noreferrer\">Le diverse fasi dello smaltimento dei rifiuti radioattivi nel video I Il progetto Cig\u00e9o<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23e3d04 elementor-widget elementor-widget-video\" data-id=\"23e3d04\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/WaKZ1_A4KQU&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd45644 elementor-mobile-align-center elementor-align-left elementor-widget elementor-widget-raven-heading\" data-id=\"dd45644\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-widget-wrapper\"><h3 class=\"raven-heading raven-heading-h3\"><span class=\"raven-heading-title \">SOLUZIONI INNOVATIVE PER IL TRATTAMENTO DI MA-VL E HA<\/span><\/h3><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9d2aa3 elementor-widget elementor-widget-text-editor\" data-id=\"c9d2aa3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n \t<li>\n<h5>UN FUTURO A BASSE EMISSIONI DI CARBONIO<\/h4>\n<\/li>\n<\/ul>\nNoi di <a href=\"https:\/\/daes.pro\/it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dares<\/a> siamo sensibili alla sfida di un futuro senza emissioni di carbonio. Per questo motivo, stiamo lavorando con <a href=\"https:\/\/www.transmutex.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">TRANSMUTEX <\/a>per rendere prioritario il trattamento delle scorie nucleari e per porre rimedio a questo limite ultimo dell&#8217;energia nucleare.\n<ul><br>\n \t<li>\n<h5>COMPETENZA DAES :<\/h5>\n<\/li>\n<\/ul>\nGrazie alla nostra lunga esperienza nel settore dell&#8217;energia nucleare, i nostri team sono in grado di simulare l&#8217;intero ciclo energetico, dalla produzione alla distribuzione. Vi supportiamo nella progettazione di prodotti e processi per i vostri progetti: riduzione\/controllo dell&#8217;inquinamento, attrezzature, ottimizzazione energetica, conformit\u00e0 ai requisiti di efficienza e normativi.\n<ul>\n \t<li>Analisi strutturale<\/li>\n \t<li>Modellazione non lineare e di contatto<\/li>\n \t<li>Impatto ed esplosione<\/li>\n \t<li>Ottimizzazione della progettazione, rumore e vibrazioni, fatica<\/li>\n \t<li>Analisi dei movimenti e dei sistemi<\/li>\n \t<li>Analisi delle sollecitazioni e dei vincoli<\/li>\n \t<li>Analisi termica e trasferimento di calore<\/li>\n \t<li>Acustica<\/li>\n<\/ul>\n<a href=\"https:\/\/daes.pro\/contact\/\" target=\"_blank\" rel=\"noopener noreferrer\">Contattateci<\/a> per maggiori informazioni o per programmare un incontro tecnico con i nostri team. <a href=\"https:\/\/www.linkedin.com\/feed\/hashtag\/insimulationwetrust\/\" target=\"_blank\" rel=\"noopener noreferrer\">#InSimulationWeTrust.<\/a>\n\n<a href=\"https:\/\/daes.pro\/it\/notizie\/webinar-simulazione-multifisica-ansys-workbench-app-m-fem-codice-rcc-m\/\">Scoprite di pi\u00f9 sulla nostra APP ANSYS sviluppata per il dimensionamento delle apparecchiature nucleari.<\/a><br><br>\n<ul>\n \t<li>\n<h5>UNA PARTNERSHIP RESPONSABILE E INNOVATIVA<\/h5>\n<\/li>\n<\/ul>\nLa soluzione <a href=\"https:\/\/www.transmutex.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Transmutex<\/a> \u00e8 una tecnologia nucleare rivoluzionaria basata sulla trasmutazione. Questo pu\u00f2 essere fatto utilizzando sistemi nucleari controllati da acceleratori. Questi sistemi accoppiati sono noti come ADS (Accelerator Driven Systems). L&#8217;ADS produce flussi di neutroni veloci per indurre la fissione degli attinidi e trasformare le specie nucleari a lunga vita (alcune centinaia di migliaia di anni) in specie a vita molto pi\u00f9 breve (alcune centinaia di anni). Questo processo genera anche energia priva di carbonio. La trasmutazione degli attinidi e dei prodotti di fissione pu\u00f2 essere effettuata in modo flessibile e molto efficiente in sistemi controllati da acceleratori.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c3fba6 elementor-widget elementor-widget-raven-image\" data-id=\"2c3fba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img decoding=\"async\" width=\"936\" height=\"597\" src=\"https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/ADS-using-Cyclotron-transmutex-blog-daes.png\" class=\"attachment-full size-full wp-image-5669\" alt=\"\" srcset=\"https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/ADS-using-Cyclotron-transmutex-blog-daes.png 936w, https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/ADS-using-Cyclotron-transmutex-blog-daes-300x191.png 300w, https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/ADS-using-Cyclotron-transmutex-blog-daes-768x490.png 768w\" sizes=\"(max-width: 936px) 100vw, 936px\" \/>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13059a3 elementor-widget elementor-widget-text-editor\" data-id=\"13059a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<ul>\n \t<li>\n<h5>TRASMUTAZIONE E RADIOTOSSICIT\u00c0<\/h5>\n<\/li>\n<\/ul>\nLa trasmutazione del combustibile irradiato ridurr\u00e0 di 100 volte la sua radiotossicit\u00e0 e di 1.000 volte il tempo di stoccaggio come scorie nucleari. Partendo da un orizzonte di stoccaggio di circa 200.000 anni, la soluzione TRANSMUTEX lo ridurrebbe a 200 anni, un periodo pi\u00f9 che accettabile viste le tecnologie esistenti che hanno dimostrato la loro validit\u00e0.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-789ae9a elementor-widget elementor-widget-text-editor\" data-id=\"789ae9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<ul>\n \t<li>\n<h4>WNE 2020 &#8211; Per una societ\u00e0 a basse emissioni di carbonio<\/h4>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad6e42a elementor-widget elementor-widget-raven-image\" data-id=\"ad6e42a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"raven-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"raven-image\">\n\t\t\n\t\t\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/daes-engineering-company-simulation-wne-2020-paris-stand-k22.png\" class=\"attachment-full size-full wp-image-5672\" alt=\"\" srcset=\"https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/daes-engineering-company-simulation-wne-2020-paris-stand-k22.png 400w, https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/daes-engineering-company-simulation-wne-2020-paris-stand-k22-300x300.png 300w, https:\/\/daes.pro\/wp-content\/uploads\/2020\/07\/daes-engineering-company-simulation-wne-2020-paris-stand-k22-150x150.png 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9791664 elementor-widget elementor-widget-text-editor\" data-id=\"9791664\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>\n<p>Prossimamente parteciperemo alla fiera <a href=\"https:\/\/www.world-nuclear-exhibition.com\/fr-fr.html\" target=\"_blank\" rel=\"noopener noreferrer\">WNE 2020<\/a>, per prendere parte alle sfide attuali e future dell&#8217;industria nucleare e per presentare un progetto promettente insieme ai team di Transmutex.<\/p>\n<p>Per rimanere aggiornati sulle nostre novit\u00e0 e sugli altri eventi DAES, seguite il nostro blog e la nostra pagina <a href=\"https:\/\/www.linkedin.com\/company\/daes-sa\" target=\"_blank\" rel=\"noopener noreferrer\">Linkedin<\/a>.<\/p>\n<p>Per ulteriori informazioni sulle nostre soluzioni, <a href=\"https:\/\/daes.pro\/contact\/\" target=\"_blank\" rel=\"noopener noreferrer\">contattateci<\/a>.<\/p>\n<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5abfd07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5abfd07\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51407f6\" data-id=\"51407f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba70af3 elementor-shape-circle e-grid-align-left e-grid-align-mobile-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"ba70af3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-c5d14e2\" href=\"https:\/\/www.facebook.com\/artbees\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-twitter elementor-repeater-item-fa3cf75\" href=\"https:\/\/twitter.com\/artbees_design?lang=en\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Twitter<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-dribbble elementor-repeater-item-caf7f1e\" href=\"https:\/\/dribbble.com\/Artbees\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Dribbble<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-dribbble\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-c98a647\" href=\"https:\/\/www.instagram.com\/artbees\/?hl=en\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rifiuti MA-VL e HA da combustibile irradiato nelle centrali nucleari Una delle principali sfide dell&#8217;energia nucleare \u00e8 la gestione e lo stoccaggio delle scorie nucleari ad alta attivit\u00e0 e a lunga vita. Rimangono pericolosamente radioattivi per centinaia di migliaia di anni (generalmente 200.000 anni) e richiedono un trattamento speciale, regolato dai governi che garantiscono la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5660,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[147],"tags":[154,148,150,151,167],"etiquettes":[],"class_list":["post-6155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articoli","tag-analisi-elettromagnetica","tag-cfd-it","tag-ingegneria-del-pensiero-progettuale","tag-nucleare","tag-termomeccanica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fabbricazione - Modelli Jupiter X<\/title>\n<meta name=\"description\" content=\"Il potente template per siti web Manufacture di Jupiter X WP Theme, con il suo design elegante, gli elementi utili e i colori vivaci, far\u00e0 risaltare il sito della vostra fabbrica e azienda manifatturiera tra la folla!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fabbricazione - Modelli Jupiter X\" \/>\n<meta property=\"og:description\" content=\"Il potente template per siti web Manufacture di Jupiter X WP Theme, con il suo design elegante, gli elementi utili e i colori vivaci, far\u00e0 risaltare il sito della vostra fabbrica e azienda manifatturiera tra la folla!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/\" \/>\n<meta property=\"og:site_name\" content=\"Development of Advanced Engineering Solutions\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-09T06:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-15T16:16:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/daes.pro\/wp-content\/uploads\/2023\/03\/piscine-gestion-dechets-nucleaire.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Abdessamad\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DAES_GENEVE\" \/>\n<meta name=\"twitter:site\" content=\"@DAES_GENEVE\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Abdessamad\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/\"},\"author\":{\"name\":\"Abdessamad\",\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/#\\\/schema\\\/person\\\/9b0b3235cbecb88d6d8380ea2c02947a\"},\"headline\":\"Tutto quello che avreste sempre voluto sapere sulla gestione delle scorie nucleari (ma che avevate paura di chiedere)!\",\"datePublished\":\"2020-07-09T06:56:00+00:00\",\"dateModified\":\"2023-11-15T16:16:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/\"},\"wordCount\":1484,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daes.pro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/piscine-gestion-dechets-nucleaire.jpg\",\"keywords\":[\"Analisi elettromagnetica\",\"CFD\",\"Ingegneria del pensiero progettuale\",\"Nucleare\",\"Termomeccanica\"],\"articleSection\":[\"Articoli\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/\",\"url\":\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/\",\"name\":\"Fabbricazione - Modelli Jupiter X\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/daes.pro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/piscine-gestion-dechets-nucleaire.jpg\",\"datePublished\":\"2020-07-09T06:56:00+00:00\",\"dateModified\":\"2023-11-15T16:16:03+00:00\",\"description\":\"Il potente template per siti web Manufacture di Jupiter X WP Theme, con il suo design elegante, gli elementi utili e i colori vivaci, far\u00e0 risaltare il sito della vostra fabbrica e azienda manifatturiera tra la folla!\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/articoli\\\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/daes.pro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/piscine-gestion-dechets-nucleaire.jpg\",\"contentUrl\":\"https:\\\/\\\/daes.pro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/piscine-gestion-dechets-nucleaire.jpg\",\"width\":900,\"height\":600,\"caption\":\"piscine gestion dechets nucleaire\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/daes.pro\\\/it\\\/\",\"name\":\"Development of Advanced Engineering Solutions\",\"description\":\"Des solutions pragmatiques pour vos d\u00e9fis d&#039;ing\u00e9nierie\",\"publisher\":{\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/daes.pro\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/#organization\",\"name\":\"DAES SA\",\"alternateName\":\"Development of Advanced Engineering Solutions\",\"url\":\"https:\\\/\\\/daes.pro\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/daes.pro\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-Logo-DAES.png\",\"contentUrl\":\"https:\\\/\\\/daes.pro\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/cropped-Logo-DAES.png\",\"width\":512,\"height\":512,\"caption\":\"DAES SA\"},\"image\":{\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/DAES_GENEVE\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/daes-sa\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbUYhhZYofJBJ8ibSBET8hA?pbjreload=101\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/daes.pro\\\/it\\\/#\\\/schema\\\/person\\\/9b0b3235cbecb88d6d8380ea2c02947a\",\"name\":\"Abdessamad\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80ebb27d34cb66412c9ddac831d8199d929304bf6aabeac5b727a218420716d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80ebb27d34cb66412c9ddac831d8199d929304bf6aabeac5b727a218420716d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80ebb27d34cb66412c9ddac831d8199d929304bf6aabeac5b727a218420716d9?s=96&d=mm&r=g\",\"caption\":\"Abdessamad\"},\"sameAs\":[\"https:\\\/\\\/daes.pro\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fabbricazione - Modelli Jupiter X","description":"Il potente template per siti web Manufacture di Jupiter X WP Theme, con il suo design elegante, gli elementi utili e i colori vivaci, far\u00e0 risaltare il sito della vostra fabbrica e azienda manifatturiera tra la folla!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/","og_locale":"it_IT","og_type":"article","og_title":"Fabbricazione - Modelli Jupiter X","og_description":"Il potente template per siti web Manufacture di Jupiter X WP Theme, con il suo design elegante, gli elementi utili e i colori vivaci, far\u00e0 risaltare il sito della vostra fabbrica e azienda manifatturiera tra la folla!","og_url":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/","og_site_name":"Development of Advanced Engineering Solutions","article_published_time":"2020-07-09T06:56:00+00:00","article_modified_time":"2023-11-15T16:16:03+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/daes.pro\/wp-content\/uploads\/2023\/03\/piscine-gestion-dechets-nucleaire.jpg","type":"image\/jpeg"}],"author":"Abdessamad","twitter_card":"summary_large_image","twitter_creator":"@DAES_GENEVE","twitter_site":"@DAES_GENEVE","twitter_misc":{"Scritto da":"Abdessamad","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/#article","isPartOf":{"@id":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/"},"author":{"name":"Abdessamad","@id":"https:\/\/daes.pro\/it\/#\/schema\/person\/9b0b3235cbecb88d6d8380ea2c02947a"},"headline":"Tutto quello che avreste sempre voluto sapere sulla gestione delle scorie nucleari (ma che avevate paura di chiedere)!","datePublished":"2020-07-09T06:56:00+00:00","dateModified":"2023-11-15T16:16:03+00:00","mainEntityOfPage":{"@id":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/"},"wordCount":1484,"commentCount":0,"publisher":{"@id":"https:\/\/daes.pro\/it\/#organization"},"image":{"@id":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/#primaryimage"},"thumbnailUrl":"https:\/\/daes.pro\/wp-content\/uploads\/2023\/03\/piscine-gestion-dechets-nucleaire.jpg","keywords":["Analisi elettromagnetica","CFD","Ingegneria del pensiero progettuale","Nucleare","Termomeccanica"],"articleSection":["Articoli"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/","url":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/","name":"Fabbricazione - Modelli Jupiter X","isPartOf":{"@id":"https:\/\/daes.pro\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/#primaryimage"},"image":{"@id":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/#primaryimage"},"thumbnailUrl":"https:\/\/daes.pro\/wp-content\/uploads\/2023\/03\/piscine-gestion-dechets-nucleaire.jpg","datePublished":"2020-07-09T06:56:00+00:00","dateModified":"2023-11-15T16:16:03+00:00","description":"Il potente template per siti web Manufacture di Jupiter X WP Theme, con il suo design elegante, gli elementi utili e i colori vivaci, far\u00e0 risaltare il sito della vostra fabbrica e azienda manifatturiera tra la folla!","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/daes.pro\/it\/articoli\/tutto-quello-che-avreste-sempre-voluto-sapere-sulla-gestione-delle-scorie-nucleari-ma-che-avevate-paura-di-chiedere\/#primaryimage","url":"https:\/\/daes.pro\/wp-content\/uploads\/2023\/03\/piscine-gestion-dechets-nucleaire.jpg","contentUrl":"https:\/\/daes.pro\/wp-content\/uploads\/2023\/03\/piscine-gestion-dechets-nucleaire.jpg","width":900,"height":600,"caption":"piscine gestion dechets nucleaire"},{"@type":"WebSite","@id":"https:\/\/daes.pro\/it\/#website","url":"https:\/\/daes.pro\/it\/","name":"Development of Advanced Engineering Solutions","description":"Des solutions pragmatiques pour vos d\u00e9fis d&#039;ing\u00e9nierie","publisher":{"@id":"https:\/\/daes.pro\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/daes.pro\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/daes.pro\/it\/#organization","name":"DAES SA","alternateName":"Development of Advanced Engineering Solutions","url":"https:\/\/daes.pro\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/daes.pro\/it\/#\/schema\/logo\/image\/","url":"https:\/\/daes.pro\/wp-content\/uploads\/2022\/09\/cropped-Logo-DAES.png","contentUrl":"https:\/\/daes.pro\/wp-content\/uploads\/2022\/09\/cropped-Logo-DAES.png","width":512,"height":512,"caption":"DAES SA"},"image":{"@id":"https:\/\/daes.pro\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/DAES_GENEVE","https:\/\/www.linkedin.com\/company\/daes-sa\/","https:\/\/www.youtube.com\/channel\/UCbUYhhZYofJBJ8ibSBET8hA?pbjreload=101"]},{"@type":"Person","@id":"https:\/\/daes.pro\/it\/#\/schema\/person\/9b0b3235cbecb88d6d8380ea2c02947a","name":"Abdessamad","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/80ebb27d34cb66412c9ddac831d8199d929304bf6aabeac5b727a218420716d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80ebb27d34cb66412c9ddac831d8199d929304bf6aabeac5b727a218420716d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80ebb27d34cb66412c9ddac831d8199d929304bf6aabeac5b727a218420716d9?s=96&d=mm&r=g","caption":"Abdessamad"},"sameAs":["https:\/\/daes.pro"]}]}},"_links":{"self":[{"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/posts\/6155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/comments?post=6155"}],"version-history":[{"count":1,"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/posts\/6155\/revisions"}],"predecessor-version":[{"id":6157,"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/posts\/6155\/revisions\/6157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/media\/5660"}],"wp:attachment":[{"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/media?parent=6155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/categories?post=6155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/tags?post=6155"},{"taxonomy":"etiquettes","embeddable":true,"href":"https:\/\/daes.pro\/it\/wp-json\/wp\/v2\/etiquettes?post=6155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}